{"id":17112,"date":"2004-02-16T03:09:09","date_gmt":"2004-02-16T03:09:09","guid":{"rendered":"http:\/\/hinternet.de\/blog\/2004\/02\/astral-doors-of-the-son-and-the-father\/"},"modified":"2022-07-05T04:34:00","modified_gmt":"2022-07-05T02:34:00","slug":"astral-doors-of-the-son-and-the-father","status":"publish","type":"post","link":"https:\/\/hinternet.de\/blog\/2004\/02\/astral-doors-of-the-son-and-the-father\/","title":{"rendered":"Astral Doors: Of The Son And The Father"},"content":{"rendered":"\n<p>Wenn die skandinavische Combo Astral Doors dem H\u00f6rer &#8222;Rainbow In Your Mind&#8220; entgegenschleudert, dann wird umgekehrt ein Schuh draus: Von wegen, Rainbow in YOUR Mind. Und weil es mit Dio so lustig war, werden hier die Pfaffen nicht in Wasser geschmissen wie bei &#8222;Holy Diver&#8220;, sondern direkt ans Kreuz genagelt.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Auch textlich hat man die Klischees von 30 Jahren Hardrock zusammengef\u00fchrt und gl\u00e4nzt mit Songtiteln wie &#8222;Slay The Dragon&#8220; oder &#8222;Night Of The Witch&#8220;. Musikalisch macht das Album trotzdem m\u00e4chtig Spa\u00df, weil die vier Jungs keine hymnischen Refrains auffahren, sondern den Spirit des 70er Jahre Hardrock sympathisch zelebrieren.<\/p>\n\n\n\n<p>&#8222;Of The Son And The Father&#8220; m\u00fcsste jedem gefallen, der sich gerne schnell heimisch f\u00fchlt und im Restaurant immer das selbe Essen bestellt.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Astral Doors: Of The Son And The Father<br \/>Locomotive<br \/>V\u00d6: 3.2.2004<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Wenn die skandinavische Combo Astral Doors dem H\u00f6rer &#8222;Rainbow In Your Mind&#8220; entgegenschleudert, dann wird umgekehrt ein Schuh draus: Von wegen, Rainbow in YOUR Mind. Und weil es mit Dio so lustig war, werden hier die Pfaffen nicht in Wasser geschmissen wie bei &#8222;Holy Diver&#8220;, sondern direkt ans Kreuz genagelt.<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","footnotes":""},"categories":[1070],"tags":[],"class_list":["post-17112","post","type-post","status-publish","format-standard","hentry","category-watching-the-detectives"],"featured_image_src":null,"author_info":{"display_name":"Dirk-Michael Mitter","author_link":"https:\/\/hinternet.de\/blog\/author\/dmm\/"},"_links":{"self":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts\/17112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/comments?post=17112"}],"version-history":[{"count":0,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts\/17112\/revisions"}],"wp:attachment":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/media?parent=17112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/categories?post=17112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/tags?post=17112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}