{"id":31645,"date":"1995-11-18T11:11:00","date_gmt":"1995-11-18T10:11:00","guid":{"rendered":"http:\/\/hinternet.de\/blog\/?p=31645"},"modified":"2022-07-17T02:57:08","modified_gmt":"2022-07-17T00:57:08","slug":"raekwon-only-built-4-cuban-linx","status":"publish","type":"post","link":"https:\/\/hinternet.de\/blog\/1995\/11\/raekwon-only-built-4-cuban-linx\/","title":{"rendered":"Raekwon: Only Built 4 Cuban Linx\u2026"},"content":{"rendered":"\n<p>The Wu-Tang Saga Continues\u2026<br \/>Shallah Raekwon&#8217;s Deb\u00fct-CD ist das neueste (hierzulande erh\u00e4ltliche) Produkt des Wu-Tang-Clans, der es sich zum Ziel gesetzt hat der gr\u00f6\u00dfte und bedeutendste Hip-Hop-Clan zu werden.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Raekwons Album schlie\u00dft am ehesten noch an Method Man&#8217;s Album an. &#8222;Only Built 4 Cuban Linx\u2026&#8220; klingt sehr entspannt und flie\u00dft ruhig vor sich hin. Produziert, gemixt und arrangiert hat wie immer RZA. Die Samples vermeiden all das, was man hierzulande noch im allgemeinen unter &#8222;fettem Hip Hop&#8220; versteht. Genau deshalb sind die Platten des Wu-Tang-Clans auch so gut. Mit irgendwelchem G-Funk oder Gangsta-Rap haben die Mitglieder des Clans nichts am Hut (trotz eingespielter Sch\u00fcsse zwischen den Liedern). Hip Hop und vor allem das Sampling wird wieder zur Kunstform entwickelt und entfaltet dadurch seine ganze St\u00e4rke und Sch\u00f6nheit. Raekwon&#8217;s Deb\u00fctalbum ist fast noch besser als das geistesverwandte Album von MOBB DEEP und er\u00f6ffnet neue Welten f\u00fcr die Entwicklung des Hip Hops in den n\u00e4chsten Jahren.<\/p>\n\n\n\n<p>Als Anspieltip sei hier nur die Remix- Version von &#8222;Can It be All so Simple&#8220;, im Original auf &#8222;Enter The Wu-Tang&#8220; (1993), und das wunderbare &#8222;Glaciers Of Ice&#8220; mit dem weiblichen Gegenpart zu Raekwon, Blue Raspberry, empfohlen. Gigantisch!<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Raekwon: Only Built 4 Cuban Linx\u2026<br \/>(RCA)<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>The Wu-Tang Saga Continues\u2026Shallah Raekwon&#8217;s Deb\u00fct-CD ist das neueste (hierzulande erh\u00e4ltliche) Produkt des Wu-Tang-Clans, der es sich zum Ziel gesetzt hat der gr\u00f6\u00dfte und bedeutendste Hip-Hop-Clan zu werden.<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-31645","post","type-post","status-publish","format-standard","hentry","category-musik"],"featured_image_src":null,"author_info":{"display_name":"Thomas Klein","author_link":"https:\/\/hinternet.de\/blog\/author\/thomas-klein\/"},"_links":{"self":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts\/31645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/comments?post=31645"}],"version-history":[{"count":0,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts\/31645\/revisions"}],"wp:attachment":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/media?parent=31645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/categories?post=31645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/tags?post=31645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}