{"id":41355,"date":"2025-05-31T00:01:00","date_gmt":"2025-05-30T22:01:00","guid":{"rendered":"https:\/\/hinternet.de\/blog\/?p=41355"},"modified":"2025-04-22T14:08:10","modified_gmt":"2025-04-22T12:08:10","slug":"kalenderblatt-31-mai-2025","status":"publish","type":"post","link":"https:\/\/hinternet.de\/blog\/2025\/05\/kalenderblatt-31-mai-2025\/","title":{"rendered":"Kalenderblatt 31. Mai 2025"},"content":{"rendered":"\n<pre class=\"wp-block-preformatted\">151. Tag des Jahres<br \/>Weltnichtrauchertag<\/pre>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Architektur ist vermutete Zukunft<\/p><cite>Frei Otto<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Vor <strong>170 Jahren<\/strong>: Theaterpremiere &#8222;<strong><em>Leonce und Lena<\/em><\/strong>&#8222;. <strong>Georg B\u00fcchners<\/strong> Kom\u00f6die wird 18 Jahre nach dem Tod des Dichters in M\u00fcnchen uraufgef\u00fchrt.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Vor <strong>50 Jahren<\/strong>: In Paris wird die <strong>Europ\u00e4ische Weltraumagentur<\/strong> ESA gegr\u00fcndet. Beteiligt sind 13 europ\u00e4ische Staaten.<\/p>\n\n\n\n<p>Vor <strong>20 Jahren<\/strong>: Nach jahrzehntelangen Mutma\u00dfungen, wer hinter &#8222;<strong><em>Deep Throat<\/em><\/strong>&#8220; &#8211; der geheimen Quelle der Reporter Woodward und Bernstein bei ihrer Aufkl\u00e4rung der Watergate-Aff\u00e4re &#8211; steckt, ver\u00f6ffentlicht das Magazin Vanity Fair einen Artikel, in dem dessen wahre Identit\u00e4t aufgedeckt wird: es war der hochrangige FBI-Mitarbeiter <strong>Mark Felt<\/strong>.<\/p>\n\n\n\n<p>Geburtstage:<\/p>\n\n\n\n<p>Vor <strong>100 Jahren<\/strong> geboren: <strong>Frei Otto<\/strong>, deutscher Architekt, der u.a. die Dachkonstruktion f\u00fcr das M\u00fcnchner Olympiastadion entwickelte. Gestorben 9.3.2015.<\/p>\n\n\n\n<p>Vor <strong>95 Jahren<\/strong> geboren: <strong>Clint Eastwood<\/strong>, US-amerikanischer Schauspieler (&#8222;F\u00fcr eine Handvoll Dollar&#8220;, &#8222;Dirty Harry&#8220;, &#8222;In the line of fire&#8220;) , Regisseur (&#8222;Sadistico&#8220;, &#8222;Pale Rider&#8220;, &#8222;Wei\u00dfer J\u00e4ger, schwarzes Herz&#8220;, &#8222;Br\u00fccken am Flu\u00df&#8220;) und Gelegenheitspolitiker. F\u00fcr seinen Western &#8222;Erbarmungslos&#8220; (1992) gabs den Regie-Oscar.<\/p>\n\n\n\n<p>Vor <strong>80 Jahren<\/strong> geboren: <strong>Rainer Werner Fassbinder<\/strong>, deutscher Filmregisseur (&#8222;Der H\u00e4ndler der vier Jahreszeiten&#8220;, &#8222;Angst essen Seele auf&#8220;, &#8222;Faustrecht der Freiheit&#8220;, &#8222;Die Ehe der Maria Braun&#8220;, &#8222;Die Sehnsucht der Veronika Voss&#8220;, &#8222;Berlin Alexanderplatz&#8220;, &#8222;Querelle&#8220;). Gestorben 10.6.1982.<\/p>\n\n\n\n<p>Vor <strong>60 Jahren<\/strong> geboren: <strong>Brooke Shields<\/strong>, US-amerikanische Schauspielerin (&#8222;Die blaue Lagune&#8220;).<\/p>\n\n\n\n<p>Vor <strong>55 Jahren<\/strong> geboren: <strong>Paolo Sorrentino<\/strong>, italienischer Regisseur (&#8222;Il Divo&#8220;, &#8222;Cheyenne \u2013 This Must Be the Place&#8220;, &#8222;La Grande Bellezza \u2013 Die gro\u00dfe Sch\u00f6nheit&#8220;).<\/p>\n\n\n\n<p>Vor <strong>45 Jahren<\/strong> geboren: <strong>Andy Hurley<\/strong>, US-amerikanischer Drummer bei Fall Out Boy (&#8222;This Ain\u00b4t a Scene, It\u00b4s an Arms Race&#8220;) und The Damned Things.<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>Todestage:<\/p>\n\n\n\n<p><strong>145. Todestag <\/strong>von <strong>Hippolyte M\u00e8ge-Mouri\u00e8s<\/strong>. Der franz\u00f6sische Erfinder der Margarine starb 62j\u00e4hrig in Paris.<\/p>\n\n\n\n<p><strong>25. Todestag <\/strong>von <strong>Johnnie Taylor<\/strong>. Der US-amerikanische S\u00e4nger (&#8222;Disco Lady&#8220;) starb 66j\u00e4hrig in einem Krankenhaus in Dallas, Texas an den Folgen eines Herzanfalls.<\/p>\n\n\n\n<p><strong>20. Todestag <\/strong>von <strong>Herbert Junck<\/strong>. Der deutsche Schlagzeuger von Silly starb 55j\u00e4hrig an Krebs.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Mehr und ausf\u00fchrlichere Daten zum 31. Mai in unserem <a href=\"https:\/\/hinternet.de\/kalender\/0531.php\">Historischen Kalender<\/a><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>151. Tag des JahresWeltnichtrauchertag Architektur ist vermutete Zukunft Frei Otto Vor 170 Jahren: Theaterpremiere &#8222;Leonce und Lena&#8222;. Georg B\u00fcchners Kom\u00f6die wird 18 Jahre nach dem Tod des Dichters in M\u00fcnchen uraufgef\u00fchrt.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-41355","post","type-post","status-publish","format-standard","hentry","category-kalender"],"featured_image_src":null,"author_info":{"display_name":"mitty","author_link":"https:\/\/hinternet.de\/blog\/author\/walt_mitty\/"},"_links":{"self":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts\/41355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/comments?post=41355"}],"version-history":[{"count":0,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts\/41355\/revisions"}],"wp:attachment":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/media?parent=41355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/categories?post=41355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/tags?post=41355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}