{"id":6499,"date":"2012-01-08T23:42:25","date_gmt":"2012-01-08T22:42:25","guid":{"rendered":"http:\/\/hinternet.de\/blog\/?p=6499"},"modified":"2012-01-09T05:48:25","modified_gmt":"2012-01-09T04:48:25","slug":"tag-8","status":"publish","type":"post","link":"https:\/\/hinternet.de\/blog\/2012\/01\/tag-8\/","title":{"rendered":"Tag 8"},"content":{"rendered":"<p>Das bislang kleinste k\u00fcnftige Ex-Exponat f\u00fchrt ins Jahr 1988. Ich war damals frisch beim Radio und die Plattenfirmen hatten noch Geld f\u00fcr allerlei Promomaterial, Gimmicks und Firlefanz. G\u00e4ngige Giveaways waren T-Shirts, Tassen, Feuerzeuge, M\u00fctzen, Tragetaschen oder Badges. (Wirklich wichtige Menschen bekamen auch kostbarere Pr\u00e4sente. Ich nicht.) Denkbar preiswert d\u00fcrfte der Werbeartikel zur &#8222;Life&#8217;s Too Good&#8220;-LP von den Sugarcubes gewesen sein:<br \/>\n<!--more--><\/p>\n<p><a href=\"https:\/\/hinternet.de\/blog\/wp-content\/uploads\/2012\/01\/tag008.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6501\" title=\"Na, S\u00fc\u00dfe, wie w\u00e4r\u00b4s mit uns\" src=\"https:\/\/hinternet.de\/blog\/wp-content\/uploads\/2012\/01\/tag008-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/hinternet.de\/blog\/wp-content\/uploads\/2012\/01\/tag008-300x200.jpg 300w, https:\/\/hinternet.de\/blog\/wp-content\/uploads\/2012\/01\/tag008-145x96.jpg 145w, https:\/\/hinternet.de\/blog\/wp-content\/uploads\/2012\/01\/tag008.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Das Deb\u00fct der Sugarcubes gefiel mir damals sehr. Ganz unabh\u00e4ngig vom s\u00fc\u00dfen Promomaterial. Die Musik war gut, die S\u00e4ngerin hatte eine beeindruckende Stimme und ihre Manierismen fand ich charmant und putzig. Wenige Jahrzehnte sp\u00e4ter sind vor allem die Manierismen geblieben und wenn ich zuletzt mal einen Auftritt von Bj\u00f6rk im Fernsehen sah erinnerte mich das meist an klingonische Oper (&#8222;&uarr;<a href=\"http:\/\/www.youtube.com\/watch?v=RIZffwddS78\" title=\"Videoausschnitt aus Star Trek - Next Generation\">Aktuh und Maylota<\/a>&#8222;).<\/p>\n<p><a href=\"https:\/\/hinternet.de\/blog\/wp-content\/uploads\/2012\/01\/tag008-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6500\" title=\"Coffee, milk and two sugarcubes\" src=\"https:\/\/hinternet.de\/blog\/wp-content\/uploads\/2012\/01\/tag008-2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/hinternet.de\/blog\/wp-content\/uploads\/2012\/01\/tag008-2-300x200.jpg 300w, https:\/\/hinternet.de\/blog\/wp-content\/uploads\/2012\/01\/tag008-2-145x96.jpg 145w, https:\/\/hinternet.de\/blog\/wp-content\/uploads\/2012\/01\/tag008-2.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Da ich keinen Kaffee trinke und meinen Tee gr\u00fcn und pur bevorzuge haben die beiden Zuckerst\u00fccke die fast zweieinhalb Jahrzehnte unbeschadet \u00fcberstanden (Zucker hat bekannterma\u00dfen kein Mindesthaltbarkeitsdatum). Potenzielle Sammler von Bj\u00f6rk-Devotionalien oder von nordatlantischen S\u00fc\u00dfstoffen haben jetzt 14 Tage Zeit, sich bei uns zu melden. Ansonsten verschwinden die beiden Saccharosequader in der Kaffeetasse eines Gastes.<\/p>\n<table  class=\"raeumung table table-hover\" >\n<tr>\n<td>Was:<\/td>\n<td>2 Zuckerw\u00fcrfel. Originalverpackt<\/td>\n<\/tr>\n<tr>\n<td>Wohin:<\/td>\n<td>An einen Sammler. Alternativ: Kaffee (Zuckerw\u00fcrfel) &#038; Altpapiertonne (Verpackung)<\/td>\n<\/tr>\n<tr>\n<td>Ersparnis:<\/td>\n<td>4g; 5,05cm<sup>3<\/sup><\/td>\n<\/tr>\n<tr>\n<td>Neupreis:<\/td>\n<td>Nada, da Promogeschenk <\/td>\n<\/tr>\n<tr>\n<td>Wiederverkaufspreis:<\/td>\n<td>Ein freundliches Danke in der Kaffeepause.<\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Das bislang kleinste k\u00fcnftige Ex-Exponat f\u00fchrt ins Jahr 1988. Ich war damals frisch beim Radio und die Plattenfirmen hatten noch Geld f\u00fcr allerlei Promomaterial, Gimmicks und Firlefanz. G\u00e4ngige Giveaways waren T-Shirts, Tassen, Feuerzeuge, M\u00fctzen, Tragetaschen oder Badges. (Wirklich wichtige Menschen bekamen auch kostbarere Pr\u00e4sente. Ich nicht.) Denkbar preiswert d\u00fcrfte der Werbeartikel zur &#8222;Life&#8217;s Too Good&#8220;-LP [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[406],"tags":[],"class_list":["post-6499","post","type-post","status-publish","format-standard","hentry","category-herr-mitty-raeumt-auf"],"featured_image_src":null,"author_info":{"display_name":"","author_link":"https:\/\/hinternet.de\/blog\/author\/"},"_links":{"self":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts\/6499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/comments?post=6499"}],"version-history":[{"count":0,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/posts\/6499\/revisions"}],"wp:attachment":[{"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/media?parent=6499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/categories?post=6499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hinternet.de\/blog\/wp-json\/wp\/v2\/tags?post=6499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}